{"id":28190,"date":"2024-09-06T15:02:31","date_gmt":"2024-09-06T13:02:31","guid":{"rendered":"https:\/\/surt.org\/?p=28190"},"modified":"2024-11-12T13:34:33","modified_gmt":"2024-11-12T11:34:33","slug":"lintro-suport-mutu-per-a-dones-supervivents-de-violencies-masclistes-2","status":"publish","type":"post","link":"https:\/\/surt.org\/es\/lintro-suport-mutu-per-a-dones-supervivents-de-violencies-masclistes-2\/","title":{"rendered":"INTRO, apoyo mutuo para mujeres supervivientes de violencias machistas"},"content":{"rendered":"<h2 class=\"wp-block-heading\">INTRO, apoyo mutuo para mujeres supervivientes de violencias machistas<\/h2>\n\n\n\n<figure><img decoding=\"async\" src=\"https:\/\/surt.org\/wp-content\/uploads\/2024\/09\/intro-2024_1100x300-1024x279.png\" alt=\"\"\/><\/figure>\n\n\n<p>El proyecto <strong>INTRO <\/strong><span class=\"Y2IQFc\" lang=\"es\">arranca este curso nuevas sesiones de ma\u00f1anas y tardes para generar un espacio de <strong>apoyo mutuo para mujeres supervivientes de violencias machistas<\/strong>. En los meses de noviembre y diciembre de 2024, el proyecto ofrecer\u00e1 herramientas de resiliencia a las participantes:<\/span><\/p>\n<ul>\n<li>Actividades orientadas hacia la generaci\u00f3n de redes de apoyo<\/li>\n<li>Herramientas para desarrollar estrategias para potenciar la autonom\u00eda y la calidad de vida<\/li>\n<li>Recursos para generar una convivencia positiva y mejorar la realidad que enfrentan las muejres en su proceso de recuperaci\u00f3n de las violencies maschistas<\/li>\n<\/ul>\n<p>Se organizar\u00e1n 2 grupos, para que las participantes escojan el turno que <span class=\"Y2IQFc\" lang=\"es\">mejor se adapte a sus necesidades:<\/span><\/p>\n<ul>\n<li><b>Del 4 de noviembre al 16 de diciembre: los lunes, de 10h a 13h<\/b><\/li>\n<li><b>Del 7 de noviembre al 19 de diciembre: los jueves, de 15.15h a 18h<\/b><\/li>\n<\/ul>\n<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Traducci\u00f3\" data-ved=\"2ahUKEwj_5IzR7bCJAxWgRUEAHaXyDqgQ3ewLegQIChAU\" aria-label=\"Text tradu\u00eft: Las sesiones se desarrollar\u00e1n en la sede\"><span class=\"Y2IQFc\" lang=\"es\">Las sesiones se desarrollar\u00e1n en la sede <\/span><span style=\"font-size: revert; color: initial;\">de la Fundaci\u00f3 Surt, en la calle Gu\u00e0rdia, 14 bajos (Barcelona).<\/span><\/p>\n<p>Las <strong>inscripciones <\/strong><span class=\"Y2IQFc\" lang=\"es\">se pueden realizar por correo (dina.agra@surt.org) o enviando un whatsapp (650 88 67 49).<\/span><\/p>\n<p>Esta acci\u00f3n cuenta con el apoyo del Departament d\u2019Igualtat i Feminisme de la Generalitat de Catalunya y del Ayuntamiento de Barcelona.<\/p>","protected":false},"excerpt":{"rendered":"<p>INTRO, apoyo mutuo para mujeres supervivientes de violencias machistas El proyecto INTRO arranca este curso nuevas sesiones de ma\u00f1anas y tardes para generar un espacio de apoyo mutuo para mujeres supervivientes de violencias machistas. En los meses de noviembre y diciembre de 2024, el proyecto ofrecer\u00e1 herramientas de resiliencia a las participantes: Actividades orientadas hacia [&hellip;]<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81],"tags":[],"class_list":["post-28190","post","type-post","status-publish","format-standard","hentry","category-actualidad-es"],"_links":{"self":[{"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/posts\/28190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/comments?post=28190"}],"version-history":[{"count":3,"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/posts\/28190\/revisions"}],"predecessor-version":[{"id":28529,"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/posts\/28190\/revisions\/28529"}],"wp:attachment":[{"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/media?parent=28190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/categories?post=28190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/tags?post=28190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}