{"id":17405,"date":"2021-10-22T08:33:27","date_gmt":"2021-10-22T07:33:27","guid":{"rendered":"https:\/\/www.surt.org\/?p=17405"},"modified":"2024-09-29T11:07:29","modified_gmt":"2024-09-29T09:07:29","slug":"surt-participa-en-un-proyecto-europeo-para-favorecer-el-empoderament-de-las-mujeres-migradas-con-una-estrategia-comunitaria","status":"publish","type":"post","link":"https:\/\/surt.org\/es\/surt-participa-en-un-proyecto-europeo-para-favorecer-el-empoderament-de-las-mujeres-migradas-con-una-estrategia-comunitaria\/","title":{"rendered":"Surt participa en un proyecto europeo para favorecer el empoderament de las mujeres migradas con una estrategia comunitaria"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"594\" height=\"361\" src=\"https:\/\/surt.org\/wp-content\/uploads\/2021\/10\/captura-3-1.jpg\" alt=\"\" class=\"wp-image-27518\" srcset=\"https:\/\/surt.org\/wp-content\/uploads\/2021\/10\/captura-3-1.jpg 594w, https:\/\/surt.org\/wp-content\/uploads\/2021\/10\/captura-3-1-300x182.jpg 300w, https:\/\/surt.org\/wp-content\/uploads\/2021\/10\/captura-3-1-18x12.jpg 18w\" sizes=\"(max-width: 594px) 100vw, 594px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Surt participa en un proyecto europeo para favorecer el empoderament de las mujeres migradas con una estrategia comunitaria<\/h2>\n\n\n<p>Surt participa en el proyecto Women4Integration: from neighbourhoods tono Europe, una iniciativa que se dirige a promover la empoderament econ\u00f3mico y personal de mujeres migradas. A partir de las experiencias de cuatro barrios de cuatro ciudades -Barcelona (Raval), \u00c1msterdam (\u00c1msterdam Oost), Mil\u00e0 (San Siro) y Malm\u00f6 (Roseng\u00e4rd)-, este proyecto europeo se propone ser un proceso de innovaci\u00f3n metodol\u00f3gica con perspectiva de g\u00e9nero y comunitaria.<\/p>\n<p>Recientemente, se ha celebrado el primer encuentro de organizaciones participantes en San Siro, durante la cual se han intercambiado conocimientos para construir una metodolog\u00eda com\u00fan que favorezca la empoderamiento de mujeres migradas. El proyecto, cofinanciado por el Fondo de Asilo, Migraci\u00f3n e Inclusi\u00f3n de la Uni\u00f3n Europea, est\u00e1 coordinado por Soleterre Onlus y cuenta con la implicaci\u00f3n de organizaciones de Italia, Pa\u00edses Bajos, Suecia y Catalu\u00f1a.<\/p>\n<p>&#8220;Nos proponemos avanzar en la incorporaci\u00f3n de una perspectiva feminista\u00a0interseccional\u00a0en las metodolog\u00edas comunitarias, arraigadas en el barrios. Trabajamos desde la perspectiva que cada mujer est\u00e1 en el centro de su proceso individual de\u00a0empoderament, pero hace falta tambi\u00e9n la implicaci\u00f3n de la comunidad, de las pol\u00edticas y los servicios p\u00fablicos, de los territorios&#8221;, explica Laura Sales, responsable del \u00e1mbito de investigaci\u00f3n de\u00a0Surt.<\/p>\n<p>En los primeros encuentros, el objetivo ser\u00e1 codise\u00f1ar un marco com\u00fan, para, posteriormente, desarrollar herramientas metodol\u00f3gicas. &#8220;El an\u00e1lisis de buenas pr\u00e1cticas y visitar experiencias de inclusi\u00f3n significativas en otros territorios solidifica el proceso de aprendizaje mutuo y reflexi\u00f3n sobre los propios proyectos&#8221;, valora Sales.<\/p>\n<p>El empoderamiento econ\u00f3mico y personal de mujeres migradas es un \u00e1mbito de trabajo que Surt desarrolla a trav\u00e9s del programa SADI (Servicio de Atenci\u00f3n a Mujeres Inmigradas).<\/p>\n<p>Acompa\u00f1a mujeres en situaciones de especial vulnerabilidad, como son aquellas que todav\u00eda no han tenido posibilidad de regularizar la situaci\u00f3n, o aquellas que han topado con la irregularidad sobrevenida, por ejemplo, cuando se les ha denegado la petici\u00f3n de asilo.\u00a0 \u201cLa meta es favorecer la igualdad efectiva\u201d, sintetiza Xantal Genovart, coordinadora del programa y profesional del proyecto Women4Integration desde Surt.<\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Surt participa en un proyecto europeo para favorecer el empoderament de las mujeres migradas con una estrategia comunitaria Surt participa en el proyecto Women4Integration: from neighbourhoods tono Europe, una iniciativa que se dirige a promover la empoderament econ\u00f3mico y personal de mujeres migradas. A partir de las experiencias de cuatro barrios de cuatro ciudades -Barcelona [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81],"tags":[],"class_list":["post-17405","post","type-post","status-publish","format-standard","hentry","category-actualidad-es"],"_links":{"self":[{"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/posts\/17405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/comments?post=17405"}],"version-history":[{"count":2,"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/posts\/17405\/revisions"}],"predecessor-version":[{"id":27520,"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/posts\/17405\/revisions\/27520"}],"wp:attachment":[{"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/media?parent=17405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/categories?post=17405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/tags?post=17405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}