{"id":24216,"date":"2024-08-20T18:05:20","date_gmt":"2024-08-20T16:05:20","guid":{"rendered":"https:\/\/devsurt.lana2.net\/?page_id=24216"},"modified":"2024-08-20T18:49:25","modified_gmt":"2024-08-20T16:49:25","slug":"consultoria-e","status":"publish","type":"page","link":"https:\/\/surt.org\/es\/empoderamiento-sociopolitico\/consultoria-e\/","title":{"rendered":"Consultoria"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"24216\" class=\"elementor elementor-24216\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b138933 e-flex e-con-boxed e-con e-parent\" data-id=\"4b138933\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f7f6914 elementor-widget elementor-widget-spacer\" data-id=\"7f7f6914\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-25e63d5 e-flex e-con-boxed e-con e-parent\" data-id=\"25e63d5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8017d69 elementor-widget elementor-widget-text-editor\" data-id=\"8017d69\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"the-title\"><span style=\"color: #e2007a;\">Consultoria<\/span><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-754b80d e-flex e-con-boxed e-con e-parent\" data-id=\"754b80d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3afd509 elementor-widget elementor-widget-text-editor\" data-id=\"3afd509\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_row vc_row vc_row-fluid mk-fullwidth-false attched-false js-master-row mk-in-viewport\"><div class=\"vc_col-sm-6 wpb_column column_container vc_custom_1491651809658 _ height-full\"><div class=\"vc_custom_1683057259296\"><div id=\"text-block-6\" class=\"mk-text-block\"><p>La Consultor\u00eda de Surt es un servicio especializado en la promoci\u00f3n y la incorporaci\u00f3n de la perspectiva de g\u00e9nero y de la diversidad sexual en organizaciones como administraciones, empresas y entidades sociales.<\/p><p>Trabajamos desde los siguientes principios operativos:<\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c062d6c e-flex e-con-boxed e-con e-parent\" data-id=\"7c062d6c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-33356fc9 e-con-full e-flex e-con e-child\" data-id=\"33356fc9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3926bf58 elementor-widget elementor-widget-text-editor\" data-id=\"3926bf58\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_row vc_row vc_row-fluid mk-fullwidth-false attched-false js-master-row mk-in-viewport\"><div class=\"vc_col-sm-6 wpb_column column_container vc_custom_1491651809658 _ height-full\"><div class=\"vc_custom_1683057259296\"><div id=\"text-block-6\" class=\"mk-text-block\"><p><strong>Igualdad de g\u00e9nero<\/strong>, basada en la igualdad de derechos y d?oportunidades entre mujeres y hombres y en la transformaci\u00f3n de las costumbres y las estructuras sociales que perpet\u00faan las desigualdades.<\/p><p><strong>Diversidad sexual y de g\u00e9nero<\/strong>, contemplamos la igualdad llena y la no discriminaci\u00f3n hacia las personas LGBTI, as\u00ed como la visibilidad y la promoci\u00f3n de las libertades sexuales y de g\u00e9nero como derecho a la ciudadan\u00eda general m\u00e1s all\u00e1 de las siglas LGTBI.<\/p><p><strong>Participaci\u00f3n<\/strong>, creemos que las personas son agentes activos de cambio y por lo tanto promovemos su implicaci\u00f3n activa en el procesos de transformaci\u00f3n.<\/p><p><strong>Innovaci\u00f3n metodol\u00f3gica<\/strong>, dise\u00f1amos metodolog\u00edas innovadoras y renovamos los m\u00e9todos y las t\u00e9cnicas para mejorar los procesos y los resultados de los productos.<\/p><p>Para cualquier pregunta o petici\u00f3n, contacta con\u00a0<strong>consultoria@surt.org<\/strong><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9049ab0 e-con-full e-flex e-con e-child\" data-id=\"9049ab0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ad6f55d elementor-widget elementor-widget-image\" data-id=\"4ad6f55d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/surt.org\/wp-content\/uploads\/2024\/08\/equinova-2.jpg\" class=\"attachment-full size-full wp-image-24202\" alt=\"\" srcset=\"https:\/\/surt.org\/wp-content\/uploads\/2024\/08\/equinova-2.jpg 1920w, https:\/\/surt.org\/wp-content\/uploads\/2024\/08\/equinova-2-300x200.jpg 300w, https:\/\/surt.org\/wp-content\/uploads\/2024\/08\/equinova-2-1024x683.jpg 1024w, https:\/\/surt.org\/wp-content\/uploads\/2024\/08\/equinova-2-1536x1024.jpg 1536w, https:\/\/surt.org\/wp-content\/uploads\/2024\/08\/equinova-2-720x480.jpg 720w, https:\/\/surt.org\/wp-content\/uploads\/2024\/08\/equinova-2-18x12.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-542cc01f e-flex e-con-boxed e-con e-parent\" data-id=\"542cc01f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-405c24d1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"405c24d1\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d9302d e-flex e-con-boxed e-con e-parent\" data-id=\"4d9302d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-98aee45 elementor-widget elementor-widget-text-editor\" data-id=\"98aee45\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"the-title\"><span style=\"color: #e2007a;\">Asesor\u00eda y elaboraci\u00f3n de productos<\/span><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a71578 elementor-widget elementor-widget-ld_accordion\" data-id=\"5a71578\" data-element_type=\"widget\" data-widget_type=\"ld_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"accordion accordion-title-bordered accordion-xs accordion-side-spacing accordion-title-bg-transparent accordion-active-has-fill\" id=\"accordion-6a03dab2c3a75\" role=\"tablist\" aria-multiselectable=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel  active\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-9481\">\n\t\t\t\t<h2 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a03dab2c3a75\" data-bs-parent=\"#accordion-6a03dab2c3a75\" href=\"#collapse-9481\" data-target=\"#collapse-9481\" data-bs-target=\"#collapse-9481\"\n\t\t\t\t\taria-expanded=\"true\" aria-controls=\"collapse-9481\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Apoyo y asesoramiento t\u00e9cnico<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"fa fa-chevron-down\"><\/i><i class=\"fa fa-chevron-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h2>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-9481\" class=\"accordion-collapse collapse  show\" data-bs-parent=\"#accordion-6a03dab2c3a75\" role=\"tabpanel\" aria-labelledby=\"heading-9481\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<h3><strong>Apoyo y asesoramiento t\u00e9cnico para la incorporaci\u00f3n de la perspectiva de g\u00e9nero y LGTB en proyectos, programas y pol\u00edticas<\/strong><\/h3><ul><li>Apoyamos y hacemos asesor\u00eda t\u00e9cnica para la aplicaci\u00f3n y el seguimiento de la perspectiva de g\u00e9nero y LGTBI en organizaciones p\u00fablicas y privadas.<\/li><li>Planes de igualdad de g\u00e9nero y LGTBI para la ciudadan\u00eda.<\/li><li>Auditor\u00edas, evaluaciones y diagn\u00f3sticos de pol\u00edticas.<\/li><li>Planes de igualdad internos para organizaciones como empresas y administraciones p\u00fablicas.<\/li><li>Reglamentos para la igualdad de g\u00e9nero y la defensa de los derechos de las personas LGTBI.<\/li><\/ul><p>\u00a0<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-9482\">\n\t\t\t\t<h2 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a03dab2c3a75\" data-bs-parent=\"#accordion-6a03dab2c3a75\" href=\"#collapse-9482\" data-target=\"#collapse-9482\" data-bs-target=\"#collapse-9482\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-9482\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Protocolos violencias machistas<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"fa fa-chevron-down\"><\/i><i class=\"fa fa-chevron-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h2>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-9482\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-6a03dab2c3a75\" role=\"tabpanel\" aria-labelledby=\"heading-9482\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<h3><strong>Protocolos de prevenci\u00f3n y abordaje de las violencias machistas\u00a0<\/strong><\/h3><ul><li>Protocolos comarcales y locales de abordaje de las violencias machistas.<\/li><li>Protocolos de acoso sexual, por raz\u00f3n de sexo y\/o por orientaci\u00f3n sexual e identidad de g\u00e9nero para organizaciones como empresas, y administraciones p\u00fablicas.<\/li><li>Protocolos contra las violencias machistas y LGTBf\u00f3bicas en espacios p\u00fablicos de ocio.<\/li><\/ul><p>\u00a0<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-9483\">\n\t\t\t\t<h2 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a03dab2c3a75\" data-bs-parent=\"#accordion-6a03dab2c3a75\" href=\"#collapse-9483\" data-target=\"#collapse-9483\" data-bs-target=\"#collapse-9483\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-9483\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Materiales y recursos<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"fa fa-chevron-down\"><\/i><i class=\"fa fa-chevron-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h2>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-9483\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-6a03dab2c3a75\" role=\"tabpanel\" aria-labelledby=\"heading-9483\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<h3><strong>Materiales y recursos<\/strong><\/h3><p>Elaboramos gu\u00edas y materiales de formaci\u00f3n y sensibilizaci\u00f3n sobre perspectiva de g\u00e9nero y LGTBI, violencias machistas y empoderamiento.<\/p><p>\u00a0<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Apoyo y asesoramiento t\\u00e9cnico\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Apoyo y asesoramiento tcnico para la incorporacin de la perspectiva de gnero y LGTB en proyectos, programas y polticasApoyamos y hacemos asesora tcnica para la aplicacin y el seguimiento de la perspectiva de gnero y LGTBI en organizaciones pblicas y privadas.Planes de igualdad de gnero y LGTBI para la ciudadana.Auditoras, evaluaciones y diagnsticos de polticas.Planes de igualdad internos para organizaciones como empresas y administraciones pblicas.Reglamentos para la igualdad de gnero y la defensa de los derechos de las personas LGTBI.\"}},{\"@type\":\"Question\",\"name\":\"Protocolos violencias machistas\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Protocolos de prevencin y abordaje de las violencias machistasProtocolos comarcales y locales de abordaje de las violencias machistas.Protocolos de acoso sexual, por razn de sexo y\\\/o por orientacin sexual e identidad de gnero para organizaciones como empresas, y administraciones pblicas.Protocolos contra las violencias machistas y LGTBfbicas en espacios pblicos de ocio.\"}},{\"@type\":\"Question\",\"name\":\"Materiales y recursos\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Materiales y recursosElaboramos guas y materiales de formacin y sensibilizacin sobre perspectiva de gnero y LGTBI, violencias machistas y empoderamiento.\"}}]}<\/script>\n\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-523ef90 e-flex e-con-boxed e-con e-parent\" data-id=\"523ef90\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e86753 elementor-widget elementor-widget-text-editor\" data-id=\"0e86753\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"the-title\"><span style=\"color: #e2007a;\">Formaci\u00f3n a profesionales<\/span><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d695951 elementor-widget elementor-widget-ld_accordion\" data-id=\"d695951\" data-element_type=\"widget\" data-widget_type=\"ld_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"accordion accordion-title-bordered accordion-xs accordion-side-spacing accordion-title-bg-transparent accordion-active-has-fill\" id=\"accordion-6a03dab2c4314\" role=\"tablist\" aria-multiselectable=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel  active\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-2251\">\n\t\t\t\t<h2 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a03dab2c4314\" data-bs-parent=\"#accordion-6a03dab2c4314\" href=\"#collapse-2251\" data-target=\"#collapse-2251\" data-bs-target=\"#collapse-2251\"\n\t\t\t\t\taria-expanded=\"true\" aria-controls=\"collapse-2251\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Transversalidad de g\u00e9nero<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"fa fa-chevron-down\"><\/i><i class=\"fa fa-chevron-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h2>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-2251\" class=\"accordion-collapse collapse  show\" data-bs-parent=\"#accordion-6a03dab2c4314\" role=\"tabpanel\" aria-labelledby=\"heading-2251\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<h3><strong>Transversalidad de la perspectiva de g\u00e9nero\u00a0<\/strong><\/h3><ul><li>Introducci\u00f3n de la perspectiva de g\u00e9nero en el ciclo de los proyectos y programas.<\/li><li>Transversalidad de la perspectiva de g\u00e9nero a las pol\u00edticas p\u00fablicas.<\/li><li>Herramientas para introducir la perspectiva de g\u00e9nero en servicios p\u00fablicos de atenci\u00f3n a personas como servicios sociales de atenci\u00f3n directa, promoci\u00f3n econ\u00f3mica, juventud y cultura entre otros.<\/li><li>Introducci\u00f3n de la perspectiva de g\u00e9nero en infancia y ocio.<\/li><li>Herramientas para la incorporaci\u00f3n de la perspectiva de g\u00e9nero a nuestras entidades.<\/li><li>Herramientas para la incorporaci\u00f3n de perspectiva de g\u00e9nero en la atenci\u00f3n a las personas en situaci\u00f3n de exclusi\u00f3n residencial.<\/li><\/ul><p>\u00a0<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-2252\">\n\t\t\t\t<h2 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a03dab2c4314\" data-bs-parent=\"#accordion-6a03dab2c4314\" href=\"#collapse-2252\" data-target=\"#collapse-2252\" data-bs-target=\"#collapse-2252\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-2252\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Diversidad sexual y de g\u00e9nero<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"fa fa-chevron-down\"><\/i><i class=\"fa fa-chevron-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h2>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-2252\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-6a03dab2c4314\" role=\"tabpanel\" aria-labelledby=\"heading-2252\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<h3><strong>Perspectiva de la diversidad sexual y de g\u00e9nero<\/strong><\/h3><ul><li>Introducci\u00f3n a la perspectiva LGBTI.<\/li><li>Claves para el dise\u00f1o y la implementaci\u00f3n de pol\u00edticas locales LGBTI.<\/li><li>Introducci\u00f3n a la perspectiva LGTBI en el \u00e1mbito laboral. Formaci\u00f3n para agentes laborales.<\/li><li>Estrategias para la mejora de la inserci\u00f3n laboral de personas trans. Formaci\u00f3n para agentes laborales.<\/li><\/ul><p>\u00a0<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-2253\">\n\t\t\t\t<h2 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a03dab2c4314\" data-bs-parent=\"#accordion-6a03dab2c4314\" href=\"#collapse-2253\" data-target=\"#collapse-2253\" data-bs-target=\"#collapse-2253\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-2253\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Violencias machistas<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"fa fa-chevron-down\"><\/i><i class=\"fa fa-chevron-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h2>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-2253\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-6a03dab2c4314\" role=\"tabpanel\" aria-labelledby=\"heading-2253\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<h3><strong>Violencias machistas<\/strong><\/h3><ul><li>Prevenci\u00f3n y abordaje de las violencias machistas en varios \u00e1mbitos.<\/li><li>Herramientas para el abordaje y la atenci\u00f3n a personas LGBTI.<\/li><li>La violencia machista. Intervenci\u00f3n con ni\u00f1os y adolescentes desde la perspectiva de g\u00e9nero.<\/li><li>Violencias machistas desde la perspectiva de g\u00e9nero e intercultural.<\/li><li>Prevenci\u00f3n de las violencias machistas a trav\u00e9s de la m\u00fasica.<\/li><li>Acoso sexual, por raz\u00f3n de sexo y\/o por orientaci\u00f3n sexual e identidad de g\u00e9nero.<\/li><\/ul><p>\u00a0<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Transversalidad de g\\u00e9nero\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Transversalidad de la perspectiva de gneroIntroduccin de la perspectiva de gnero en el ciclo de los proyectos y programas.Transversalidad de la perspectiva de gnero a las polticas pblicas.Herramientas para introducir la perspectiva de gnero en servicios pblicos de atencin a personas como servicios sociales de atencin directa, promocin econmica, juventud y cultura entre otros.Introduccin de la perspectiva de gnero en infancia y ocio.Herramientas para la incorporacin de la perspectiva de gnero a nuestras entidades.Herramientas para la incorporacin de perspectiva de gnero en la atencin a las personas en situacin de exclusin residencial.\"}},{\"@type\":\"Question\",\"name\":\"Diversidad sexual y de g\\u00e9nero\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Perspectiva de la diversidad sexual y de gneroIntroduccin a la perspectiva LGBTI.Claves para el diseo y la implementacin de polticas locales LGBTI.Introduccin a la perspectiva LGTBI en el mbito laboral. Formacin para agentes laborales.Estrategias para la mejora de la insercin laboral de personas trans. Formacin para agentes laborales.\"}},{\"@type\":\"Question\",\"name\":\"Violencias machistas\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Violencias machistasPrevencin y abordaje de las violencias machistas en varios mbitos.Herramientas para el abordaje y la atencin a personas LGBTI.La violencia machista. Intervencin con nios y adolescentes desde la perspectiva de gnero.Violencias machistas desde la perspectiva de gnero e intercultural.Prevencin de las violencias machistas a travs de la msica.Acoso sexual, por razn de sexo y\\\/o por orientacin sexual e identidad de gnero.\"}}]}<\/script>\n\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fcae949 e-flex e-con-boxed e-con e-parent\" data-id=\"fcae949\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1040d5 elementor-widget elementor-widget-text-editor\" data-id=\"b1040d5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"the-title\"><span style=\"color: #e2007a;\">Experiencias destacadas<\/span><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77b2627 elementor-widget elementor-widget-ld_accordion\" data-id=\"77b2627\" data-element_type=\"widget\" data-widget_type=\"ld_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"accordion accordion-title-bordered accordion-xs accordion-side-spacing accordion-title-bg-transparent accordion-active-has-fill\" id=\"accordion-6a03dab2c4b8c\" role=\"tablist\" aria-multiselectable=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel  active\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1251\">\n\t\t\t\t<h2 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a03dab2c4b8c\" data-bs-parent=\"#accordion-6a03dab2c4b8c\" href=\"#collapse-1251\" data-target=\"#collapse-1251\" data-bs-target=\"#collapse-1251\"\n\t\t\t\t\taria-expanded=\"true\" aria-controls=\"collapse-1251\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Apoyo y asesor\u00eda t\u00e9cnica<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"fa fa-chevron-down\"><\/i><i class=\"fa fa-chevron-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h2>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1251\" class=\"accordion-collapse collapse  show\" data-bs-parent=\"#accordion-6a03dab2c4b8c\" role=\"tabpanel\" aria-labelledby=\"heading-1251\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p><strong>II Plan de Igualdad Interno del Consejo Insular de Menorca (2020-2024)\u00a0<\/strong><\/p><p>Con el objetivo de promover un cambio organizativo que posibilite que los hombres y las mujeres que trabajan al Consejo Insular de Menorca puedan desarrollar su carrera profesional sin que se d\u00e9 ning\u00fan tipo de discriminaci\u00f3n por raz\u00f3n de g\u00e9nero, se lleva a cabo el II Plan de Igualdad Interno, que guiar\u00e1 la pol\u00edtica de personal para los pr\u00f3ximos a\u00f1os. Este Plan se desarroll\u00f3, principalmente, de forma on-line, adaptando nuestra metodolog\u00eda al formato virtual.<\/p><p><strong><a href=\"http:\/\/www.cime.es\/documents\/documents\/4484docpub.pdf\">II Plan de Igualdad Interno\u00a0<\/a><\/strong><\/p><p><strong><a href=\"http:\/\/www.cime.es\/Contingut.aspx?IDPUB=82442\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a0Noticia de aprobaci\u00f3n<\/a><\/strong><\/p><p>\u00a0<\/p><p><strong>II Plan de Igualdad Interno del Ayuntamiento de Granollers (2020-2024)<\/strong><\/p><p>Con el objetivo de fomentar la equidad de g\u00e9nero dentro del Ayuntamiento de Granollers y que, a la vez, se desarrollaran acciones alineadas con el Plan de igualdad de ciudadan\u00eda, el II Plan de Igualdad Interno fue un proceso participativo donde colaboraron m\u00faltiples agentes (mandos, representaci\u00f3n sindical, trabajadores y trabajadoras\u2026). El Pla consta de once ejes de an\u00e1lisis que guiar\u00e1n las acciones internas de promoci\u00f3n de la igualdad de g\u00e9nero hasta el a\u00f1o 2024.<\/p><p><strong><a href=\"https:\/\/www.naciodigital.cat\/naciogranollers\/noticia\/30967\/granollers\/aprova\/segon\/pla\/igualtat\/intern\/ajuntament\" target=\"_blank\" rel=\"noopener noreferrer\">Leer noticia\u00a0<\/a><\/strong><\/p><p>\u00a0<\/p><p><strong>I Plan de diversidad, equidad e inclusi\u00f3n de la Universidad Miguel Hern\u00e1ndez de Elche (2019).<\/strong><\/p><p>Este plan innovador, actualmente en proceso de elaboraci\u00f3n, adopta un enfoque interseccional y una mirada amplia que incluye diferentes dis\u00adcriminacions y ejes de desigualdad. Adem\u00e1s del g\u00e9nero y la sexualidad, el plan contempla \u00a0la diversidad funcional, la raza o procedencia y la lengua para fomentar una comunidad universitaria libre y preparada para atender la diversidad.<\/p><p><a href=\"https:\/\/comunicacion.umh.es\/2019\/06\/27\/puesta-en-marcha-del-i-plan-de-diversidad-equidad-e-inclusion\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Leer nota de prensa<\/strong><\/a><\/p><p><strong>\u00a0<\/strong><\/p><p><strong>Plan local para la diversidad sexual, afectiva y de g\u00e9nero. Ayuntamiento del Prat de Llobregat (2019-2023).<\/strong><\/p><p>Este plan local es una herramienta indispensable para trabajar de manera transversal para la promoci\u00f3n de la igualdad de las personas LGTBI. Adem\u00e1s, dado que el movimiento LGTBI tiende a centrarse en la experiencia de los hombres gays mientras que las experiencias de las mujeres lesbianas, las personas trans y las personas bisexuales se mantienen m\u00e1s invisibilizadas. En consecuencia, este plan incorpora un enfoque feminista que vuelve visibles las diferencias y las desigualdades entre las personas LGTBI. As\u00ed mismo, se entiende como herramienta para trabajar de manera transversal y promover el principio de igualdad en el conjunto de actuaciones.<\/p><p>[Pr\u00f3ximamente disponible per descarregar]<\/p><p>\u00a0<\/p><p><strong>Antenas de igualdad. Estrategia para la transversalidad de g\u00e9nero en las pol\u00edticas y servicios municipales del Ayuntamiento de Sant Boi de Llobregat (2019).<\/strong><\/p><p>La estrategia de las Antenas de igualdad surge a ra\u00edz del II Plan de igualdad Interno (2018-2021) del Ayuntamiento de Sant Boi de Llobregat. Se trata de una estrategia para la implementaci\u00f3n de la transversalidad de g\u00e9nero en las pol\u00edticas y servicios municipales. Se dirige a las personas que participan en el dise\u00f1o y la ejecuci\u00f3n de las pol\u00edticas locales, especialmente al personal t\u00e9cnico no especializado en igualdad de g\u00e9nero; y busca as\u00ed contribuir al desarrollo de una pol\u00edtica y una ciudad m\u00e1s igualitaria.<\/p><p><a href=\"http:\/\/www.santboi.cat\/NPremsaW.nsf\/ca-WebNPremsa-BASE\/C12570A40043BB01C12583A000322AFF?OpenDocument&amp;Clau=tnoticies&amp;Idioma=ca&amp;Seu=N\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Leer nota de prensa<\/strong><\/a><\/p><p>\u00a0<\/p><p><strong>III Plan de igualdad de g\u00e9nero para la ciudad de Sant Boi de Llobregat (2019-2023).<\/strong><\/p><p>Se trata del principal instrumento de las pol\u00edticas de igualdad de g\u00e9nero en la ciudad de Sant Boi, dirigido a la ciudadan\u00eda. El plan incorpora la perspectiva de g\u00e9nero de forma transversal y atiende a la perspectiva interseccional al responder a las discriminaciones que sufren las mujeres, no s\u00f3lo por el hecho de ser mujeres, sino tambi\u00e9n como consecuencia de su etnia, procedencia, clase social, edad, diversidad funcional, y\/o de tener una sexualidad, una identidad y expresi\u00f3n de g\u00e9nero no normativa. Aborda l\u00edneas estrat\u00e9gicas diversas como la acci\u00f3n contra las violencias machistas, el impulso de una ciudad inclusiva desde la perspectiva de g\u00e9nero y la reformulaci\u00f3n de los trabajos y de los tiempos entre otros.<\/p><p><a href=\"http:\/\/www.santboi.cat\/fotos\/dones\/PIG%20Sant%20Boi.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Descargar el plan<\/strong><\/a><\/p><p>\u00a0<\/p><p><strong>Plan de igualdad de g\u00e9nero y LGTBI para la promoci\u00f3n de la diversidad afectiva, sexual y de g\u00e9nero Sabadell (2018-2022).<\/strong><\/p><p>Se trata de un plan innovador que articula la igualdad entre hombres y mujeres y la igualdad hacia las personas LGTBI, puesto que parte de la idea que ambas desigualdades tienen una ra\u00edz com\u00fan. Por lo tanto, este plan define un conjunto integrado y sistem\u00e1tico de acciones y medidas para la promoci\u00f3n de la igualdad de g\u00e9nero y la no discriminaci\u00f3n hacia las personas LGTBI.<\/p><p><a href=\"http:\/\/fitxers.sabadell.cat\/transparencia\/2018\/008345-PlaIgualtatGenereLGTBI822.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Descargar el plan<\/strong><\/a><\/p><p>\u00a0<\/p><p><strong>Reglamento para la igualdad de g\u00e9nero y la defensa y promoci\u00f3n de los derechos de las personas LGTBI del Ayuntamiento de Sabadell (2018).<\/strong><\/p><p>El objetivo del reglamento es promover la igualdad de g\u00e9nero y la eliminaci\u00f3n de todas las formas de discriminaci\u00f3n por raz\u00f3n de g\u00e9nero, a trav\u00e9s del establecimiento de un r\u00e9gimen jur\u00eddico de la igualdad de g\u00e9nero en el \u00e1mbito municipal, en l\u00ednea con el marco normativo vigente. Se trata de un documento marco a trav\u00e9s del cual poder fijar las bases de la pol\u00edtica local de igualdad en relaci\u00f3n a sus principios y objetivos, su estructura y la definici\u00f3n de las principales l\u00edneas de intervenci\u00f3n. El Reglamento representa la base sobre la cual se pueden generar estrategias m\u00e1s concretas para el desarrollo de la pol\u00edtica de igualdad.<\/p><p><strong>\u00a0<\/strong><\/p><p><strong>Estudio de la brecha salarial de g\u00e9nero del Ayuntamiento de Parets del Vall\u00e8s (2018)<\/strong><\/p><p>La Ley Org\u00e1nica 3\/2007 por la igualdad efectiva de hombres y mujeres, indica que la administraci\u00f3n local ha establecido medidas efectivas para eliminar cualquier tipo de discriminaci\u00f3n retributiva, directa o indirecta, por raz\u00f3n de sexo. En este sentido, este estudio, que deriva del Plan interno de igualdad de g\u00e9nero (2017), \u00a0es una acci\u00f3n que permite ver el grado de igualdad y las diferencias salariales entre hombres y mujeres que ocupan un mismo lugar de trabajo en el ayuntamiento, y as\u00ed poder hacer una actuaci\u00f3n adaptada a sus necesidades espec\u00edficas.<\/p><p>\u00a0<\/p><p><strong>Plan Interno de igualdad de g\u00e9nero del Ayuntamiento de Sant Boi (2017-2021)<\/strong><\/p><p>El plan interno marca la hoja de ruta de las acciones a realizar para la promoci\u00f3n de un cambio organizativo hacia una mayor igualdad de g\u00e9nero. En primer lugar, busca identificar \u00a0los obst\u00e1culos existentes para lograr la equidad de g\u00e9nero y en segundo lugar, promover la equidad de g\u00e9nero en la cultura organizativa, en los diferentes \u00e1mbitos de la organizaci\u00f3n y en el funcionamiento del Ayuntamiento.<\/p><p><a href=\"https:\/\/seu2.santboi.cat\/govern-obert\/tramits-dinformacio-publica\/ple-19-12-2017-aprovacio-inicial-del-pla-digualtat-de-genere-de-lajuntament-de-sant-boi-de-llobregat-m271-u224-2017-000002\/pla-daccio-vinculat-al-pla-digualtat-de-genere-de-lajuntament-de-sant-boi-de-llobregat\/at_download\/file\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Descargar el plan<\/strong><\/a><\/p><p>\u00a0<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1252\">\n\t\t\t\t<h2 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a03dab2c4b8c\" data-bs-parent=\"#accordion-6a03dab2c4b8c\" href=\"#collapse-1252\" data-target=\"#collapse-1252\" data-bs-target=\"#collapse-1252\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1252\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Formaciones<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"fa fa-chevron-down\"><\/i><i class=\"fa fa-chevron-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h2>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1252\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-6a03dab2c4b8c\" role=\"tabpanel\" aria-labelledby=\"heading-1252\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p><strong>Incorporaci\u00f3 de la perspectiva de g\u00e8nere a les organitzacions<\/strong><\/p><p>A trav\u00e9s d\u2019aquestes formacions treballem:<\/p><ul><li><ul><li><ul><li><ul><li><ul><li>Sensibilitzar sobre la import\u00e0ncia d\u2019adoptar la perspectiva de g\u00e8nere, i aportar elements per tal de conceptualitzar i interioritzar-la.<\/li><li>Con\u00e8ixer i saber analitzar les desigualtats de g\u00e8nere i fer-ho aprofundint en la mirada interseccional, per tal d\u2019abordar la major diversitat possible d\u2019eixos de discriminaci\u00f3 i privilegi, coherentment amb la complexitat de la realitat que tenim.<\/li><li>Contribuir a eradicar les pautes de comportament i de relaci\u00f3 fonamentades en els rols de g\u00e8nere, en els estereotips sexistes i en la masculinitat i feminitat hegem\u00f2niques, tot explorant rols socials i models alternatius de relaci\u00f3.<\/li><li>Introduir algunes eines pr\u00e0ctiques i adaptades a la realitat per a introduir la perspectiva de g\u00e8nere en el treball quotidi\u00e0 de les persones participants.<\/li><\/ul><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/li><\/ul><p>\u00a0<\/p><p><strong>Ampliant la mirada sobre les viol\u00e8ncies de g\u00e8nere. Eines per a l\u2019abordatge i l\u2019atenci\u00f3 a persones LGBTI (2019).<\/strong><\/p><p>Aquest curs, adre\u00e7at a professionals de serveis especialitzats d\u2019atenci\u00f3, es proposa millorar el coneixement\u00a0professional sobre les viol\u00e8ncies espec\u00edfiques que viuen les persones LGBTI des de la perspectiva feminista i interseccional, desenvolupar estrat\u00e8gies\u00a0d\u2019atenci\u00f3 i acompanyament a persones LGTBI en el marc dels serveis d\u2019abordatge de les viol\u00e8ncies masclistes i dels recursos de diversitat sexual, afectiva i de g\u00e8nere i generar un espai participatiu\u00a0de debat i intercanvi de coneixements entre professionals per a treballar les principals dificultats en relaci\u00f3 a la detecci\u00f3, la derivaci\u00f3 i la coordinaci\u00f3.<\/p><p><a href=\"https:\/\/surt.org\/wp-content\/uploads\/2024\/08\/programa-formaci-look-wide_surt.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Descarregar el programa\u00a0<\/strong><\/a><\/p><p>\u00a0<\/p><p><strong>Estrat\u00e8gies per a la millora de la inserci\u00f3 laboral de persones trans. Formaci\u00f3 per a agents laborals (2018).<\/strong><\/p><p>Aquesta formaci\u00f3 est\u00e0 dirigida a la millora del coneixement dels i les agents laborals de la ciutat\u00a0sobre la situaci\u00f3 espec\u00edfica de les persones trans al mercat de treball, des d\u2019una vessant te\u00f2rica i pr\u00e0ctica, posant el focus en les desigualtats i necessitats de les dones trans. Tamb\u00e9 t\u00e9 l\u2019objectiu de proporcionar als i les professionals del m\u00f3n de l\u2019ocupaci\u00f3 eines pr\u00e0ctiques\u00a0per millorar les estrat\u00e8gies d\u2019atenci\u00f3 i acompanyament a persones trans en els processos d\u2019inserci\u00f3 laboral i, alhora, de generar un espai participatiu de debat, intercanvi de coneixements i bones pr\u00e0ctiques\u00a0entre agents laborals i persones LGTBI expertes en la promoci\u00f3 dels drets de les persones trans en l\u2019\u00e0mbit laboral.<\/p><p><a href=\"https:\/\/surt.org\/wp-content\/uploads\/2024\/08\/programa-formaci-trans-laboral.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Descarregar el programa<\/strong><\/a><\/p><p>\u00a0<\/p><p><strong>Introducci\u00f3 a la perspectiva LGTBI en l\u2019\u00e0mbit laboral. Formaci\u00f3 per agents laborals (2017).<\/strong><\/p><p>L\u2019objectiu general del curs \u00e9s promoure la incorporaci\u00f3 de la perspectiva de la diversitat sexual i de g\u00e8nere i la sensibilitzaci\u00f3 espec\u00edfica envers els drets i discriminacions de les persones LGTBI en l\u2019\u00e0mbit laboral a traves de la millorar el coneixement dels agents laborals, l\u2019acompanyar en el disseny i posada en pr\u00e0ctica d\u2019actuacions pilot per la promoci\u00f3 de la diversitat sexual i de g\u00e8nere en el seu context laboral i la creaci\u00f3 d\u2019un espai d\u2019 intercanvi de coneixements i bones pr\u00e0ctiques entre agents laborals i persones expertes en la promoci\u00f3 dels drets de les persones LGTBI en l\u2019\u00e0mbit laboral.<\/p><p><a href=\"https:\/\/surt.org\/wp-content\/uploads\/2024\/08\/programa-formaci-agents-laborals-2.pdf\"><strong>Descarregar el programa<\/strong><\/a><\/p><p>\u00a0<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1253\">\n\t\t\t\t<h2 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a03dab2c4b8c\" data-bs-parent=\"#accordion-6a03dab2c4b8c\" href=\"#collapse-1253\" data-target=\"#collapse-1253\" data-bs-target=\"#collapse-1253\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1253\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Materiales y recursos<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"fa fa-chevron-down\"><\/i><i class=\"fa fa-chevron-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h2>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1253\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-6a03dab2c4b8c\" role=\"tabpanel\" aria-labelledby=\"heading-1253\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p><strong>Guia de recomanacions per al bon tracte de les persones LGTBI en l\u2019entorn laboral (2018).<\/strong><\/p><p>Es tracta d\u2019una eina dirigida a prevenir i detectar vulneracions dels drets a la feina i a promoure mesures que garanteixin la igualtat de tracte i d\u2019oportunitats de les persones LGTBI.<\/p><p><a href=\"http:\/\/www.caib.es\/govern\/rest\/arxiu\/3701958\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Descarregar la guia<\/strong><\/a><\/p><p>\u00a0<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Apoyo y asesor\\u00eda t\\u00e9cnica\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"II Plan de Igualdad Interno del Consejo Insular de Menorca (2020-2024)Con el objetivo de promover un cambio organizativo que posibilite que los hombres y las mujeres que trabajan al Consejo Insular de Menorca puedan desarrollar su carrera profesional sin que se d ningn tipo de discriminacin por razn de gnero, se lleva a cabo el II Plan de Igualdad Interno, que guiar la poltica de personal para los prximos aos. Este Plan se desarroll, principalmente, de forma on-line, adaptando nuestra metodologa al formato virtual.II Plan de Igualdad InternoNoticia de aprobacinII Plan de Igualdad Interno del Ayuntamiento de Granollers (2020-2024)Con el objetivo de fomentar la equidad de gnero dentro del Ayuntamiento de Granollers y que, a la vez, se desarrollaran acciones alineadas con el Plan de igualdad de ciudadana, el II Plan de Igualdad Interno fue un proceso participativo donde colaboraron mltiples agentes (mandos, representacin sindical, trabajadores y trabajadoras). El Pla consta de once ejes de anlisis que guiarn las acciones internas de promocin de la igualdad de gnero hasta el ao 2024.Leer noticiaI Plan de diversidad, equidad e inclusin de la Universidad Miguel Hernndez de Elche (2019).Este plan innovador, actualmente en proceso de elaboracin, adopta un enfoque interseccional y una mirada amplia que incluye diferentes discriminacions y ejes de desigualdad. Adems del gnero y la sexualidad, el plan contempla la diversidad funcional, la raza o procedencia y la lengua para fomentar una comunidad universitaria libre y preparada para atender la diversidad.Leer nota de prensaPlan local para la diversidad sexual, afectiva y de gnero. Ayuntamiento del Prat de Llobregat (2019-2023).Este plan local es una herramienta indispensable para trabajar de manera transversal para la promocin de la igualdad de las personas LGTBI. Adems, dado que el movimiento LGTBI tiende a centrarse en la experiencia de los hombres gays mientras que las experiencias de las mujeres lesbianas, las personas trans y las personas bisexuales se mantienen ms invisibilizadas. En consecuencia, este plan incorpora un enfoque feminista que vuelve visibles las diferencias y las desigualdades entre las personas LGTBI. As mismo, se entiende como herramienta para trabajar de manera transversal y promover el principio de igualdad en el conjunto de actuaciones.[Prximamente disponible per descarregar]Antenas de igualdad. Estrategia para la transversalidad de gnero en las polticas y servicios municipales del Ayuntamiento de Sant Boi de Llobregat (2019).La estrategia de las Antenas de igualdad surge a raz del II Plan de igualdad Interno (2018-2021) del Ayuntamiento de Sant Boi de Llobregat. Se trata de una estrategia para la implementacin de la transversalidad de gnero en las polticas y servicios municipales. Se dirige a las personas que participan en el diseo y la ejecucin de las polticas locales, especialmente al personal tcnico no especializado en igualdad de gnero; y busca as contribuir al desarrollo de una poltica y una ciudad ms igualitaria.Leer nota de prensaIII Plan de igualdad de gnero para la ciudad de Sant Boi de Llobregat (2019-2023).Se trata del principal instrumento de las polticas de igualdad de gnero en la ciudad de Sant Boi, dirigido a la ciudadana. El plan incorpora la perspectiva de gnero de forma transversal y atiende a la perspectiva interseccional al responder a las discriminaciones que sufren las mujeres, no slo por el hecho de ser mujeres, sino tambin como consecuencia de su etnia, procedencia, clase social, edad, diversidad funcional, y\\\/o de tener una sexualidad, una identidad y expresin de gnero no normativa. Aborda lneas estratgicas diversas como la accin contra las violencias machistas, el impulso de una ciudad inclusiva desde la perspectiva de gnero y la reformulacin de los trabajos y de los tiempos entre otros.Descargar el planPlan de igualdad de gnero y LGTBI para la promocin de la diversidad afectiva, sexual y de gnero Sabadell (2018-2022).Se trata de un plan innovador que articula la igualdad entre hombres y mujeres y la igualdad hacia las personas LGTBI, puesto que parte de la idea que ambas desigualdades tienen una raz comn. Por lo tanto, este plan define un conjunto integrado y sistemtico de acciones y medidas para la promocin de la igualdad de gnero y la no discriminacin hacia las personas LGTBI.Descargar el planReglamento para la igualdad de gnero y la defensa y promocin de los derechos de las personas LGTBI del Ayuntamiento de Sabadell (2018).El objetivo del reglamento es promover la igualdad de gnero y la eliminacin de todas las formas de discriminacin por razn de gnero, a travs del establecimiento de un rgimen jurdico de la igualdad de gnero en el mbito municipal, en lnea con el marco normativo vigente. Se trata de un documento marco a travs del cual poder fijar las bases de la poltica local de igualdad en relacin a sus principios y objetivos, su estructura y la definicin de las principales lneas de intervencin. El Reglamento representa la base sobre la cual se pueden generar estrategias ms concretas para el desarrollo de la poltica de igualdad.Estudio de la brecha salarial de gnero del Ayuntamiento de Parets del Valls (2018)La Ley Orgnica 3\\\/2007 por la igualdad efectiva de hombres y mujeres, indica que la administracin local ha establecido medidas efectivas para eliminar cualquier tipo de discriminacin retributiva, directa o indirecta, por razn de sexo. En este sentido, este estudio, que deriva del Plan interno de igualdad de gnero (2017), es una accin que permite ver el grado de igualdad y las diferencias salariales entre hombres y mujeres que ocupan un mismo lugar de trabajo en el ayuntamiento, y as poder hacer una actuacin adaptada a sus necesidades especficas.Plan Interno de igualdad de gnero del Ayuntamiento de Sant Boi (2017-2021)El plan interno marca la hoja de ruta de las acciones a realizar para la promocin de un cambio organizativo hacia una mayor igualdad de gnero. En primer lugar, busca identificar los obstculos existentes para lograr la equidad de gnero y en segundo lugar, promover la equidad de gnero en la cultura organizativa, en los diferentes mbitos de la organizacin y en el funcionamiento del Ayuntamiento.Descargar el plan\"}},{\"@type\":\"Question\",\"name\":\"Formaciones\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Incorporaci de la perspectiva de gnere a les organitzacionsA travs daquestes formacions treballem:Sensibilitzar sobre la importncia dadoptar la perspectiva de gnere, i aportar elements per tal de conceptualitzar i interioritzar-la.Conixer i saber analitzar les desigualtats de gnere i fer-ho aprofundint en la mirada interseccional, per tal dabordar la major diversitat possible deixos de discriminaci i privilegi, coherentment amb la complexitat de la realitat que tenim.Contribuir a eradicar les pautes de comportament i de relaci fonamentades en els rols de gnere, en els estereotips sexistes i en la masculinitat i feminitat hegemniques, tot explorant rols socials i models alternatius de relaci.Introduir algunes eines prctiques i adaptades a la realitat per a introduir la perspectiva de gnere en el treball quotidi de les persones participants.Ampliant la mirada sobre les violncies de gnere. Eines per a labordatge i latenci a persones LGBTI (2019).Aquest curs, adreat a professionals de serveis especialitzats datenci, es proposa millorar el coneixementprofessional sobre les violncies especfiques que viuen les persones LGBTI des de la perspectiva feminista i interseccional, desenvolupar estratgiesdatenci i acompanyament a persones LGTBI en el marc dels serveis dabordatge de les violncies masclistes i dels recursos de diversitat sexual, afectiva i de gnere i generar un espai participatiude debat i intercanvi de coneixements entre professionals per a treballar les principals dificultats en relaci a la detecci, la derivaci i la coordinaci.Descarregar el programaEstratgies per a la millora de la inserci laboral de persones trans. Formaci per a agents laborals (2018).Aquesta formaci est dirigida a la millora del coneixement dels i les agents laborals de la ciutatsobre la situaci especfica de les persones trans al mercat de treball, des duna vessant terica i prctica, posant el focus en les desigualtats i necessitats de les dones trans. Tamb t lobjectiu de proporcionar als i les professionals del mn de locupaci eines prctiquesper millorar les estratgies datenci i acompanyament a persones trans en els processos dinserci laboral i, alhora, de generar un espai participatiu de debat, intercanvi de coneixements i bones prctiquesentre agents laborals i persones LGTBI expertes en la promoci dels drets de les persones trans en lmbit laboral.Descarregar el programaIntroducci a la perspectiva LGTBI en lmbit laboral. Formaci per agents laborals (2017).Lobjectiu general del curs s promoure la incorporaci de la perspectiva de la diversitat sexual i de gnere i la sensibilitzaci especfica envers els drets i discriminacions de les persones LGTBI en lmbit laboral a traves de la millorar el coneixement dels agents laborals, lacompanyar en el disseny i posada en prctica dactuacions pilot per la promoci de la diversitat sexual i de gnere en el seu context laboral i la creaci dun espai d intercanvi de coneixements i bones prctiques entre agents laborals i persones expertes en la promoci dels drets de les persones LGTBI en lmbit laboral.Descarregar el programa\"}},{\"@type\":\"Question\",\"name\":\"Materiales y recursos\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Guia de recomanacions per al bon tracte de les persones LGTBI en lentorn laboral (2018).Es tracta duna eina dirigida a prevenir i detectar vulneracions dels drets a la feina i a promoure mesures que garanteixin la igualtat de tracte i doportunitats de les persones LGTBI.Descarregar la guia\"}}]}<\/script>\n\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c4a812 e-flex e-con-boxed e-con e-parent\" data-id=\"4c4a812\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab2762b elementor-widget elementor-widget-spacer\" data-id=\"ab2762b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Consultoria La Consultor\u00eda de Surt es un servicio especializado en la promoci\u00f3n y la incorporaci\u00f3n de la perspectiva de g\u00e9nero y de la diversidad sexual en organizaciones como administraciones, empresas y entidades sociales. Trabajamos desde los siguientes principios operativos: Igualdad de g\u00e9nero, basada en la igualdad de derechos y d?oportunidades entre mujeres y hombres y [&hellip;]<\/p>","protected":false},"author":1,"featured_media":13175,"parent":24174,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-24216","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/pages\/24216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/comments?post=24216"}],"version-history":[{"count":10,"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/pages\/24216\/revisions"}],"predecessor-version":[{"id":24227,"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/pages\/24216\/revisions\/24227"}],"up":[{"embeddable":true,"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/pages\/24174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/media\/13175"}],"wp:attachment":[{"href":"https:\/\/surt.org\/es\/wp-json\/wp\/v2\/media?parent=24216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}